{"id":43204,"date":"2021-06-07T12:10:04","date_gmt":"2021-06-07T16:10:04","guid":{"rendered":"https:\/\/flexigolf.ca\/?post_type=product&#038;p=43204"},"modified":"2022-03-13T18:24:25","modified_gmt":"2022-03-13T22:24:25","slug":"casquette-new-era-flexigolf","status":"publish","type":"product","link":"https:\/\/flexigolf.ca\/en\/product\/casquette-new-era-flexigolf\/","title":{"rendered":"Casquette New Era FlexiGolf"},"content":{"rendered":"<h1 style=\"text-align: center;\">Repr\u00e9sentez FlexiGolf partout o\u00f9 vous aller et surtout encouragez la Fondation FlexiGolf<\/h1>\n<p>La fondation Flexigolf a pour mission d<span style=\"font-weight: 400;\">\u00e9mocratiser le golf afin d\u2019initier les moins privil\u00e9gi\u00e9s de la soci\u00e9t\u00e9 \u00e0 ce sport et soutenir la rel\u00e8ve qui souhaite pousser plus loin leur passion, mais dont les moyens manquent.<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/fondation.flexigolf.ca\/\">https:\/\/fondation.flexigolf.ca\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<h2 style=\"text-align: center;\">Casquette New Era FlexiGolf<\/h2>\n<p>Une seule grandeur et une seule couleur!<\/p>\n<p>Un look parfait pour les golfeurs nomades avec style \ud83d\ude42 <strong>Avec l&#8217;achat, 2$ est remis \u00e0 la Fondation FlexiGolf!<\/strong><\/p>\n<p><em>Co\u00fbt de livraison : 10$ &#8211; Achat plus de 75$, la livraison est gratuite!<\/em><\/p>\n","protected":false},"featured_media":130798,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[3487,3757],"product_tag":[],"class_list":["post-43204","product","type-product","status-publish","has-post-thumbnail","product_cat-articles-promotionnels","product_cat-casquette","product_shipping_class-casquettes","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/flexigolf.ca\/en\/wp-json\/wp\/v2\/product\/43204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flexigolf.ca\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/flexigolf.ca\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flexigolf.ca\/en\/wp-json\/wp\/v2\/media\/130798"}],"wp:attachment":[{"href":"https:\/\/flexigolf.ca\/en\/wp-json\/wp\/v2\/media?parent=43204"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/flexigolf.ca\/en\/wp-json\/wp\/v2\/product_brand?post=43204"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/flexigolf.ca\/en\/wp-json\/wp\/v2\/product_cat?post=43204"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/flexigolf.ca\/en\/wp-json\/wp\/v2\/product_tag?post=43204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}